{"id":160354,"date":"2026-07-27T06:46:27","date_gmt":"2026-07-27T06:46:27","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/07\/tenis-asics-gel-outsider-feminino-bege-bege-tam-35\/"},"modified":"2026-07-27T06:46:27","modified_gmt":"2026-07-27T06:46:27","slug":"tenis-asics-gel-outsider-feminino-bege-bege-tam-35","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/07\/tenis-asics-gel-outsider-feminino-bege-bege-tam-35\/","title":{"rendered":"T\u00eanis ASICS GEL-Outsider &#8211; Feminino &#8211; Bege\/Bege &#8211; tam: 35"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de T\u00eanis ASICS GEL-Outsider &#8211; Feminino &#8211; Bege\/Bege &#8211; tam: 35 no dia acima especificado era de <strong>R$ 599.99<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=45343891929&#038;a=690303&#038;m=23659\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/23659.png\" alt=\"T\u00eanis ASICS GEL-Outsider - Feminino - Bege\/Bege - tam: 35\" \/> &#8211; nas lojas ASICS BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/asicsbr.vteximg.com.br\/arquivos\/ids\/3618861\/1202A510_200_SR_RT_ALA.jpg?v=638867214441870000\" alt=\"T\u00eanis ASICS GEL-Outsider - Feminino - Bege\/Bege - tam: 35\" \/><br \/>\nO GEL-Outsider\u2122 foi pensado para consumidores que buscam a est\u00e9tica retro dos arquivos da ASICS e as propriedades de amortecimento de nossa linha de performance. S\u00e3o impulsionados pela hist\u00f3ria e a inspira\u00e7\u00e3o de design que carregam.Silhueta cl\u00e1ssica inspirada nos arquivos ASICS, seu tooling inspirado no GEL-Shinobi\u2122 trabalha com uma mistura de materiais no cabedal, trazendo tecido em camur\u00e7a com um visual mais casual e o ripstop deixando mais resistente Entressola trabalhando EVA com a tecnologia GEL\u2122 vis\u00edvel no calcanhar para mais amortecimento e conforto e seu solado tem borracha resistente a abras\u00e3o, melhorando a durabilidade do cal\u00e7ado.-<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/T\u00eanis ASICS GEL-Outsider - Feminino - Bege\/Bege - tam: 35\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=T\u00eanis ASICS GEL-Outsider - Feminino - Bege\/Bege - tam: 35#gsc.tab=0&amp;gsc.q=T\u00eanis ASICS GEL-Outsider - Feminino - Bege\/Bege - tam: 35&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">T\u00eanis ASICS GEL-Outsider &#8211; Feminino &#8211; Bege\/Bege &#8211; tam: 35, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>COD25523443611670075225433416610770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 599.99 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=45343891929&#038;a=690303&#038;m=23659\" target=\"_blank\" rel=\"sponsored\">ASICS BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[229,5973],"class_list":["post-160354","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-599-99","tag-asics-br"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/160354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=160354"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/160354\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=160354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=160354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=160354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}