{"id":254646,"date":"2026-07-16T13:57:42","date_gmt":"2026-07-16T13:57:42","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/07\/mochila-carrinho-embutido-notebook-2-em-1-sestini-harvest-preto-2\/"},"modified":"2026-07-16T13:57:42","modified_gmt":"2026-07-16T13:57:42","slug":"mochila-carrinho-embutido-notebook-2-em-1-sestini-harvest-preto-2","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/07\/mochila-carrinho-embutido-notebook-2-em-1-sestini-harvest-preto-2\/","title":{"rendered":"Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto"},"content":{"rendered":"<h2>Mochila > Mochilas Carrinho<\/h2>\n<h3>O pre\u00e7o de Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto no dia acima especificado era de <strong>R$ 399.90<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=35185806209&#038;a=690303&#038;m=17910\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/17910.png\" alt=\"Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto\" \/> &#8211; nas lojas Sestini BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/sestini.vteximg.com.br\/arquivos\/ids\/267911_2\" alt=\"Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto\" \/><br \/>\nDesenvolvida para quem busca versatilidade e conforto, a mochila Sestini Harvest 2 em 1 \u00e9 a solu\u00e7\u00e3o ideal para o seu cotidiano, seja no trabalho, estudo ou viagens r\u00e1pidas. Com seu sistema inovador, ela se adapta facilmente \u00e0 sua necessidade, transformando-se de mochila de costas em uma pr\u00e1tica mala de carrinho.Seu design inteligente, aliado \u00e0 robustez do poli\u00e9ster, garante que seus pertences estejam sempre protegidos, enquanto o compartimento dedicado ao notebook oferece a seguran\u00e7a que sua tecnologia merece. Al\u00e7as e costas espumadas proporcionam um transporte agrad\u00e1vel, mesmo quando precisar carregar peso.Sistema 2 em 1: versatilidade para usar como mochila de costas ou com carrinho embutido.Conforto superior: al\u00e7as e costas espumadas que minimizam o impacto nos ombros.Organiza\u00e7\u00e3o inteligente: compartimento espec\u00edfico para notebook e bolsos organizadores.Seguran\u00e7a refor\u00e7ada: puxadores com trava para cadeado, protegendo seus itens valiosos.Material resistente: fabricada em poli\u00e9ster de alta durabilidade para o uso di\u00e1rio e prolongado.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto#gsc.tab=0&amp;gsc.q=Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Mochila Carrinho Embutido Notebook 2 em 1 Sestini Harvest Preto, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>COD25523443611670075225433416610770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 399.90 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=35185806209&#038;a=690303&#038;m=17910\" target=\"_blank\" rel=\"sponsored\">Sestini BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2585,6039,37],"class_list":["post-254646","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-399-90","tag-mochila-mochilas-carrinho","tag-sestini-br"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/254646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=254646"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/254646\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=254646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=254646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=254646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}