{"id":263691,"date":"2026-07-01T17:07:24","date_gmt":"2026-07-01T17:07:24","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/07\/chinelo-ipanema-cristal-preto\/"},"modified":"2026-07-01T17:07:24","modified_gmt":"2026-07-01T17:07:24","slug":"chinelo-ipanema-cristal-preto","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/07\/chinelo-ipanema-cristal-preto\/","title":{"rendered":"Chinelo Ipanema Cristal Preto"},"content":{"rendered":"<h2>Vestu\u00e1rio e acess\u00f3rios > Roupas<\/h2>\n<h3>O pre\u00e7o de Chinelo Ipanema Cristal Preto no dia acima especificado era de <strong>R$ 34.99<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=38934294963&#038;a=690303&#038;m=17634\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/17634.png\" alt=\"Chinelo Ipanema Cristal Preto\" \/> &#8211; nas lojas Posthaus BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.posthaus.com.br\/static\/public\/produtos\/calcado-feminino\/chinelo\/chinelo-ipanema-cristal-preto_383285_600_1.jpg\" alt=\"Chinelo Ipanema Cristal Preto\" \/><br \/>\nO Chinelo Ipanema Cristal em PVC \u00e9 sin\u00f4nimo de eleg\u00e2ncia e conforto. Com seu solado flex\u00edvel, ele se adapta perfeitamente ao seu p\u00e9, ideal para dias de sol e passeios \u00e0 beira-mar. Sinta a leveza e o estilo a cada passo!<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Chinelo Ipanema Cristal Preto\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Chinelo Ipanema Cristal Preto#gsc.tab=0&amp;gsc.q=Chinelo Ipanema Cristal Preto&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Chinelo Ipanema Cristal Preto, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>COD25523443611670075225433416610770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 34.99 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=38934294963&#038;a=690303&#038;m=17634\" target=\"_blank\" rel=\"sponsored\">Posthaus BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3296,14455,14456],"class_list":["post-263691","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-34-99","tag-posthaus-br","tag-vestuario-e-acessorios-roupas"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/263691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=263691"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/263691\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=263691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=263691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=263691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}