{"id":270348,"date":"2026-07-16T10:01:37","date_gmt":"2026-07-16T10:01:37","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/07\/blusa-basica-de-manga-curta-preto\/"},"modified":"2026-07-16T10:01:37","modified_gmt":"2026-07-16T10:01:37","slug":"blusa-basica-de-manga-curta-preto","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/07\/blusa-basica-de-manga-curta-preto\/","title":{"rendered":"Blusa B\u00e1sica de Manga Curta Preto"},"content":{"rendered":"<h2>Vestu\u00e1rio e acess\u00f3rios > Roupas<\/h2>\n<h3>O pre\u00e7o de Blusa B\u00e1sica de Manga Curta Preto no dia acima especificado era de <strong>R$ 39.92<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=37413164540&#038;a=690303&#038;m=17634\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/17634.png\" alt=\"Blusa B\u00e1sica de Manga Curta Preto\" \/> &#8211; nas lojas Posthaus BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.posthaus.com.br\/static\/public\/produtos\/moda-feminina\/blusa-manga-curta\/blusa-basica-de-manga-curta-preto_720037_600_1.jpg\" alt=\"Blusa B\u00e1sica de Manga Curta Preto\" \/><br \/>\nBlusa b\u00e1sica de mangas curtas para adultos. Pe\u00e7a confeccionada em malha canelada, busca combinar estilo e conforto de maneira impec\u00e1vel. Possui uma gola alta, oferecendo um toque de eleg\u00e2ncia discreta. Seja para um dia casual ou como base para um look mais elaborado, esta pe\u00e7a esbanja simplicidade e versatilidade.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Blusa B\u00e1sica de Manga Curta Preto\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Blusa B\u00e1sica de Manga Curta Preto#gsc.tab=0&amp;gsc.q=Blusa B\u00e1sica de Manga Curta Preto&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Blusa B\u00e1sica de Manga Curta Preto, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>COD25523443611670075225433416610770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 39.92 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=37413164540&#038;a=690303&#038;m=17634\" target=\"_blank\" rel=\"sponsored\">Posthaus BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[14812,14455,14456],"class_list":["post-270348","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-39-92","tag-posthaus-br","tag-vestuario-e-acessorios-roupas"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/270348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=270348"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/270348\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=270348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=270348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=270348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}