{"id":276111,"date":"2026-07-30T04:47:07","date_gmt":"2026-07-30T04:47:07","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/07\/blusa-frente-unica-branco-2\/"},"modified":"2026-07-30T04:47:07","modified_gmt":"2026-07-30T04:47:07","slug":"blusa-frente-unica-branco-2","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/07\/blusa-frente-unica-branco-2\/","title":{"rendered":"Blusa Frente \u00danica Branco"},"content":{"rendered":"<h2>Vestu\u00e1rio e acess\u00f3rios > Roupas<\/h2>\n<h3>O pre\u00e7o de Blusa Frente \u00danica Branco no dia acima especificado era de <strong>R$ 52.45<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=44634173352&#038;a=690303&#038;m=17634\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/17634.png\" alt=\"Blusa Frente \u00danica Branco\" \/> &#8211; nas lojas Posthaus BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.posthaus.com.br\/static\/public\/produtos\/moda-feminina\/bata\/blusa-frente-unica-branco_851838_600_1.jpg\" alt=\"Blusa Frente \u00danica Branco\" \/><br \/>\nBlusa frente \u00fanica em tecido leve com amarra\u00e7\u00e3o posterior. Possui decote halter que valoriza os ombros e modelagem soltinha que traz fluidez e conforto. O detalhe das costas abertas confere um toque moderno e sofisticado, perfeita para looks elegantes e descomplicados.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Blusa Frente \u00danica Branco\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Blusa Frente \u00danica Branco#gsc.tab=0&amp;gsc.q=Blusa Frente \u00danica Branco&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Blusa Frente \u00danica Branco, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>COD25523443611670075225433416610770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 52.45 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=44634173352&#038;a=690303&#038;m=17634\" target=\"_blank\" rel=\"sponsored\">Posthaus BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[14806,14455,14456],"class_list":["post-276111","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-52-45","tag-posthaus-br","tag-vestuario-e-acessorios-roupas"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/276111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=276111"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/276111\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=276111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=276111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=276111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}