{"id":300468,"date":"2026-07-22T21:58:26","date_gmt":"2026-07-22T21:58:26","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/07\/saia-moletom-infantil-preto\/"},"modified":"2026-07-22T21:58:26","modified_gmt":"2026-07-22T21:58:26","slug":"saia-moletom-infantil-preto","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/07\/saia-moletom-infantil-preto\/","title":{"rendered":"Saia Moletom Infantil Preto"},"content":{"rendered":"<h2>Vestu\u00e1rio e acess\u00f3rios > Roupas<\/h2>\n<h3>O pre\u00e7o de Saia Moletom Infantil Preto no dia acima especificado era de <strong>R$ 29.99<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=40792092658&#038;a=690303&#038;m=17634\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/17634.png\" alt=\"Saia Moletom Infantil Preto\" \/> &#8211; nas lojas Posthaus BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.posthaus.com.br\/static\/public\/produtos\/roupa-para-menina\/saia-curta\/saia-moletom-infantil-preto_775799_600_1.jpg\" alt=\"Saia Moletom Infantil Preto\" \/><br \/>\nA Saia Infantil de Moletom Turminha e Cia apresenta uma composi\u00e7\u00e3o t\u00eaxtil que privilegia o conforto t\u00e9rmico e a maciez, ideal para climas amenos ou dias mais frescos. A modelagem tradicional da pe\u00e7a, aliada ao c\u00f3s el\u00e1stico, proporciona excelente caimento e liberdade de movimentos, adaptando-se \u00e0 anatomia infantil de maneira ergon\u00f4mica. Confeccionada em moletom de alta qualidade. Modelagem tradicional.C\u00f3s com el\u00e1stico embutido.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Saia Moletom Infantil Preto\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Saia Moletom Infantil Preto#gsc.tab=0&amp;gsc.q=Saia Moletom Infantil Preto&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Saia Moletom Infantil Preto, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>COD25523443611670075225433416610770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 29.99 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=40792092658&#038;a=690303&#038;m=17634\" target=\"_blank\" rel=\"sponsored\">Posthaus BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[198,14455,14456],"class_list":["post-300468","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-29-99","tag-posthaus-br","tag-vestuario-e-acessorios-roupas"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/300468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=300468"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/300468\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=300468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=300468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=300468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}