{"id":303868,"date":"2026-07-28T23:40:27","date_gmt":"2026-07-28T23:40:27","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/07\/vestido-infantil-menina-folhas-preto\/"},"modified":"2026-07-28T23:40:27","modified_gmt":"2026-07-28T23:40:27","slug":"vestido-infantil-menina-folhas-preto","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/07\/vestido-infantil-menina-folhas-preto\/","title":{"rendered":"Vestido Infantil Menina Folhas Preto"},"content":{"rendered":"<h2>Vestu\u00e1rio e acess\u00f3rios > Roupas<\/h2>\n<h3>O pre\u00e7o de Vestido Infantil Menina Folhas Preto no dia acima especificado era de <strong>R$ 86.45<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=44927795812&#038;a=690303&#038;m=17634\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/17634.png\" alt=\"Vestido Infantil Menina Folhas Preto\" \/> &#8211; nas lojas Posthaus BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.posthaus.com.br\/static\/public\/produtos\/roupa-para-menina\/vestido-de-inverno\/vestido-infantil-menina-folhas-preto_855491_600_1.jpg\" alt=\"Vestido Infantil Menina Folhas Preto\" \/><br \/>\nO vestido infantil menina Nanai \u00e9 a escolha perfeita para vestir a inf\u00e2ncia com cor. A estampa inspirada na natureza combina folhagem exuberante com flores estilizadas em uma composi\u00e7\u00e3o harmoniosa e vibrante. Confeccionado em moletinho 100% algod\u00e3o. A modelagem ampla com recorte na altura do busto. As mangas longas proporcionam versatilidade para diferentes esta\u00e7\u00f5es, o franzido delicado abaixo do recorte. A combina\u00e7\u00e3o entre estampa de folhas e flores cria um visual sofisticado.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Vestido Infantil Menina Folhas Preto\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Vestido Infantil Menina Folhas Preto#gsc.tab=0&amp;gsc.q=Vestido Infantil Menina Folhas Preto&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Vestido Infantil Menina Folhas Preto, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n<p>COD25523443611670075225433416610770<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R$ 86.45 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=44927795812&#038;a=690303&#038;m=17634\" target=\"_blank\" rel=\"sponsored\">Posthaus BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[15389,14455,14456],"class_list":["post-303868","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-86-45","tag-posthaus-br","tag-vestuario-e-acessorios-roupas"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/303868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=303868"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/303868\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=303868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=303868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=303868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}