{"id":71161,"date":"2026-03-09T08:02:11","date_gmt":"2026-03-09T08:02:11","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/03\/09\/conjunto-sala-de-jantar-2-banquetas-palermo-carraro-branco-prata\/"},"modified":"2026-03-09T08:02:11","modified_gmt":"2026-03-09T08:02:11","slug":"conjunto-sala-de-jantar-2-banquetas-palermo-carraro-branco-prata","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/03\/09\/conjunto-sala-de-jantar-2-banquetas-palermo-carraro-branco-prata\/","title":{"rendered":"Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata"},"content":{"rendered":"<h2><\/h2>\n<h3>O pre\u00e7o de Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata no dia acima especificado era de <strong>R$ 576.08<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=43036517415&#038;a=690303&#038;m=81383\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/81383.png\" alt=\"Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata\" \/> &#8211; nas lojas Carraro BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"\" alt=\"Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata\" \/><\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata#gsc.tab=0&amp;gsc.q=Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Conjunto Sala de Jantar 2 Banquetas Palermo Carraro Branco Prata, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>R$ 576.08 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=43036517415&#038;a=690303&#038;m=81383\" target=\"_blank\" rel=\"sponsored\">Carraro BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[98,44],"class_list":["post-71161","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-576-08","tag-carraro-br"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/71161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=71161"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/71161\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=71161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=71161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=71161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}