{"id":80876,"date":"2026-03-23T07:08:06","date_gmt":"2026-03-23T07:08:06","guid":{"rendered":"https:\/\/jr1.com.br\/shopping\/2026\/03\/23\/perfume-rabanne-phantom-intense-masculino-eau-de-parfum-refil-200-ml\/"},"modified":"2026-03-23T07:08:06","modified_gmt":"2026-03-23T07:08:06","slug":"perfume-rabanne-phantom-intense-masculino-eau-de-parfum-refil-200-ml","status":"publish","type":"post","link":"https:\/\/jr1.com.br\/shopping\/2026\/03\/23\/perfume-rabanne-phantom-intense-masculino-eau-de-parfum-refil-200-ml\/","title":{"rendered":"Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml"},"content":{"rendered":"<h2>Perfumes<\/h2>\n<h3>O pre\u00e7o de Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml no dia acima especificado era de <strong>R$ 978.90<\/strong>.<\/h3>\n<p>Confira o pre\u00e7o atual aqui: <a href=\"https:\/\/www.awin1.com\/pclick.php?p=39025454489&#038;a=690303&#038;m=100869\" rel=\"noopener sponsored\"><img decoding=\"async\" src=\"https:\/\/ui.awin.com\/images\/upload\/merchant\/profile\/100869.png\" alt=\"Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml\" \/> &#8211; nas lojas AMOBELEZA BR<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/amobeleza.vteximg.com.br\/arquivos\/ids\/273848_2\" alt=\"Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml\" \/><br \/>\nO Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil de 200 ml, conta com um sistema de refil inovador, f\u00e1cil e limpo, n\u00e3o sendo necess\u00e1rio o uso de funil. Nesse processo voc\u00ea n\u00e3o perde nenhuma gota do perfume e refor\u00e7a seu compromisso ambiental. O Perfume Rabanne Phantom Intense Masculino Eau de Parfum, \u00e9 um \u00c2mbar Amadeirado Arom\u00e1tico. Desde 1966, Rabanne tem sido uma marca pioneira, conhecida por sua moda vanguardista e seus perfumes audaciosos, ela desafia constantemente as conven\u00e7\u00f5es e empurra os limites da autoexpress\u00e3o. Vision\u00e1ria. Radical. Disruptiva. Empoderada. Inovadora. Este ano, a Maison perpetua esse legado ao transformar os c\u00f3digos e abrir caminho para uma nova era em beleza, \u00fanica em sua ess\u00eancia. Criada para incentivar e libertar a autoafirma\u00e7\u00e3o, Rabanne Beauty convida as novas gera\u00e7\u00f5es \u00e0 emancipa\u00e7\u00e3o e a ultrapassar os limites da criatividade. Transcenda as conven\u00e7\u00f5es com a fragr\u00e2ncia excepcional para o perigoso infrator dentro de si que se rende \u00e0 emo\u00e7\u00e3o da chamada noturna Phantom. Elaborado com o m\u00e1ximo refinamento, o Phantom Parfum de Rabanne \u00e9 formulado de forma respons\u00e1vel com os ingredientes selecionados, de origem \u00e9tica e potentes. Pir\u00e2mide Olfativa Notas de Topo: Flor de laranjeira, lim\u00e3o e \u00f3leo de cardamomo, c\u00edtricos com um aroma \u00fanico. Notas de Corpo: \u00d3leo de lavanda, \u00f3leo de s\u00e1lvia e rum, ingredientes preciosos e intensos. Notas de Fundo: Fava de baunilha, \u00f3leo de cedro e musgo moderno, aroma viciante e sensual.<\/p>\n<h4>Aproveite e pesquise o pre\u00e7o deste produto em dezenas de lojas dos marketplaces abaixo:<\/h4>\n<p><a href=\"https:\/\/www.magazinevoce.com.br\/magazineezu\/busca\/Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/mvc.mlcdn.com.br\/ad\/2503_superofertas.png\" alt=\"Pesquise no Magazine eZu\" \/> &#8211; da Parceria MAGALU<\/a>.<\/p>\n<p>Ainda n\u00e3o encontrou a melhor op\u00e7\u00e3o de compra? Oferecemos mais uma possibilidade de <strong>busca<\/strong> mais ampla para <a href=\"https:\/\/ecompare.com.br\/lojas\/resultados-da-pesquisa\/?q=Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml#gsc.tab=0&amp;gsc.q=Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml&amp;gsc.page=1\" target=\"_blank\" rel=\"noopener\">Perfume Rabanne Phantom Intense Masculino Eau de Parfum Refil 200 ml, clique e continue <strong>pesquisando&#8230;<\/strong><\/a><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>R$ 978.90 nas lojas <a href=\"https:\/\/www.awin1.com\/pclick.php?p=39025454489&#038;a=690303&#038;m=100869\" target=\"_blank\" rel=\"sponsored\">AMOBELEZA BR<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2548,22],"class_list":["post-80876","post","type-post","status-publish","format-standard","hentry","category-produtos","tag-978-90","tag-amobeleza-br"],"_links":{"self":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/80876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/comments?post=80876"}],"version-history":[{"count":0,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/posts\/80876\/revisions"}],"wp:attachment":[{"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/media?parent=80876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/categories?post=80876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jr1.com.br\/shopping\/wp-json\/wp\/v2\/tags?post=80876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}